{"id":1492,"date":"2025-08-03T08:23:24","date_gmt":"2025-08-03T06:23:24","guid":{"rendered":"https:\/\/souldance.be\/?post_type=team&#038;p=1492"},"modified":"2025-11-07T15:10:39","modified_gmt":"2025-11-07T14:10:39","slug":"nele-vandezande","status":"publish","type":"team","link":"https:\/\/souldance.be\/fr\/team\/nele-vandezande\/","title":{"rendered":"Nele Vandezande"},"featured_media":6833,"parent":0,"menu_order":0,"template":"","begeleiders":[29,32,33,28],"class_list":["post-1492","team","type-team","status-publish","has-post-thumbnail","hentry","begeleiders-internationale-lesgevers","begeleiders-bestuur","begeleiders-groepspraktijk","begeleiders-lesgevers-begeleiders"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-23 01:28:30","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"begeleiders","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/souldance.be\/fr\/wp-json\/wp\/v2\/team\/1492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/souldance.be\/fr\/wp-json\/wp\/v2\/team"}],"about":[{"href":"https:\/\/souldance.be\/fr\/wp-json\/wp\/v2\/types\/team"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/souldance.be\/fr\/wp-json\/wp\/v2\/media\/6833"}],"wp:attachment":[{"href":"https:\/\/souldance.be\/fr\/wp-json\/wp\/v2\/media?parent=1492"}],"wp:term":[{"taxonomy":"begeleiders","embeddable":true,"href":"https:\/\/souldance.be\/fr\/wp-json\/wp\/v2\/begeleiders?post=1492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}