{"id":10974,"date":"2026-05-09T15:00:21","date_gmt":"2026-05-09T13:00:21","guid":{"rendered":"https:\/\/souldance.be\/cursussen\/cef2-zonder-cl-enkel-professionele-modules\/"},"modified":"2026-05-13T19:00:16","modified_gmt":"2026-05-13T17:00:16","slug":"cef2-zonder-cl-enkel-professionele-modules","status":"publish","type":"courses","link":"https:\/\/souldance.be\/fr\/cursussen\/cef2-zonder-cl-enkel-professionele-modules\/","title":{"rendered":"CEF2 &#8211; zonder CL enkel professionele modules"},"content":{"rendered":"<p>Welkom in CEF 2<\/p>\n<p>&nbsp;<\/p>\n<p><strong>PROFESSIONELE MODULE<\/strong><\/p>\n<p>Module 1 : 10\/09, 1\/10, 22\/10, 12\/11 &#8211; do &#8211; 9u30-16u30.<\/p>\n<p>Module 2 : 3\/12, 21\/01, 18\/02, 18\/03 &#8211; do &#8211; 9u30-16u30.<\/p>\n<p>Stage : 17\/04 &#8211; zat &#8211; 9u-30 &#8211; 12u30.<\/p>\n<p>Module 3 : 22\/04, 13\/05 &#8211; do &#8211; 9u30-16u30.<\/p>\n<p>Scriptie : 18\/06 &#8211; vrij &#8211; 9u-30- 16u30.<\/p>\n<p>Afstudeerceremonie &amp; feest &nbsp;: zat 26\/06 &#8211; 17u.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>SESSIES<\/strong><\/p>\n<p>2 Reflectie en evaluatiesessies : Individueel , af te spreken met de toegewezen begeleider<\/p>\n<p>2 Centering Practitioner sessies : Individueel , af te spreken met de toegewezen begeleider<\/p>\n<p>3 Scriptie begeleidingssessies via zoom Individueel : Groep, Anja geeft nog de data door.<\/p>","protected":false},"template":"","class_list":["post-10974","courses","type-courses","status-publish","hentry"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 19:11:39","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/souldance.be\/fr\/wp-json\/wp\/v2\/courses\/10974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/souldance.be\/fr\/wp-json\/wp\/v2\/courses"}],"about":[{"href":"https:\/\/souldance.be\/fr\/wp-json\/wp\/v2\/types\/courses"}],"version-history":[{"count":1,"href":"https:\/\/souldance.be\/fr\/wp-json\/wp\/v2\/courses\/10974\/revisions"}],"predecessor-version":[{"id":10982,"href":"https:\/\/souldance.be\/fr\/wp-json\/wp\/v2\/courses\/10974\/revisions\/10982"}],"wp:attachment":[{"href":"https:\/\/souldance.be\/fr\/wp-json\/wp\/v2\/media?parent=10974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}