{"id":1498,"date":"2025-09-03T08:26:12","date_gmt":"2025-09-03T06:26:12","guid":{"rendered":"https:\/\/souldance.be\/?post_type=team&#038;p=1498"},"modified":"2025-09-29T08:22:20","modified_gmt":"2025-09-29T06:22:20","slug":"kristien-viaene","status":"publish","type":"team","link":"https:\/\/souldance.be\/en\/team\/kristien-viaene\/","title":{"rendered":"Kristien Viaene"},"featured_media":7339,"parent":0,"menu_order":0,"template":"","begeleiders":[28,32],"class_list":["post-1498","team","type-team","status-publish","has-post-thumbnail","hentry","begeleiders-lesgevers-begeleiders","begeleiders-bestuur"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-23 01:29:43","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"begeleiders","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/souldance.be\/en\/wp-json\/wp\/v2\/team\/1498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/souldance.be\/en\/wp-json\/wp\/v2\/team"}],"about":[{"href":"https:\/\/souldance.be\/en\/wp-json\/wp\/v2\/types\/team"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/souldance.be\/en\/wp-json\/wp\/v2\/media\/7339"}],"wp:attachment":[{"href":"https:\/\/souldance.be\/en\/wp-json\/wp\/v2\/media?parent=1498"}],"wp:term":[{"taxonomy":"begeleiders","embeddable":true,"href":"https:\/\/souldance.be\/en\/wp-json\/wp\/v2\/begeleiders?post=1498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}